{"id":2517,"date":"2019-02-09T11:35:40","date_gmt":"2019-02-09T10:35:40","guid":{"rendered":"http:\/\/biog.adview.network\/dt_testimonials\/josef-hoeckner\/"},"modified":"2019-02-09T11:35:40","modified_gmt":"2019-02-09T10:35:40","slug":"josef-hoeckner","status":"publish","type":"dt_testimonials","link":"https:\/\/biog-biogas.com\/it\/dt_testimonials\/josef-hoeckner\/","title":{"rendered":"Josef H\u00f6ckner"},"content":{"rendered":"<p>Siamo diventati specialisti nell\u2019utilizzo di residui in diverse forme e strutture. Grazie al nostro know-how aiutiamo a realizzare in modo semplice ed economico la catena di valore dal raccolto fino all\u2019impiego nel processo di fermentazione.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Siamo diventati specialisti nell\u2019utilizzo di residui in diverse forme e strutture. Grazie al nostro know-how aiutiamo a realizzare in modo semplice ed economico la catena di valore dal raccolto fino all\u2019impiego nel processo di fermentazione.<\/p>\n","protected":false},"featured_media":535,"template":"","dt_testimonials_category":[46],"class_list":["post-2517","dt_testimonials","type-dt_testimonials","status-publish","has-post-thumbnail","hentry","dt_testimonials_category-azienda","dt_testimonials_category-46","description-off"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Josef H\u00f6ckner - BIOG<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/biog-biogas.com\/it\/dt_testimonials\/josef-hoeckner\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Josef H\u00f6ckner - BIOG\" \/>\n<meta property=\"og:description\" content=\"Siamo diventati specialisti nell\u2019utilizzo di residui in diverse forme e strutture. Grazie al nostro know-how aiutiamo a realizzare in modo semplice ed economico la catena di valore dal raccolto fino all\u2019impiego nel processo di fermentazione.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/biog-biogas.com\/it\/dt_testimonials\/josef-hoeckner\/\" \/>\n<meta property=\"og:site_name\" content=\"BIOG\" \/>\n<meta property=\"og:image\" content=\"https:\/\/biog-biogas.com\/wp-content\/uploads\/josef-hoeckner-mit-feldresten.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1618\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/biog-biogas.com\\\/it\\\/dt_testimonials\\\/josef-hoeckner\\\/\",\"url\":\"https:\\\/\\\/biog-biogas.com\\\/it\\\/dt_testimonials\\\/josef-hoeckner\\\/\",\"name\":\"Josef H\u00f6ckner - BIOG\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/biog-biogas.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/biog-biogas.com\\\/it\\\/dt_testimonials\\\/josef-hoeckner\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/biog-biogas.com\\\/it\\\/dt_testimonials\\\/josef-hoeckner\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/biog-biogas.com\\\/wp-content\\\/uploads\\\/josef-hoeckner-mit-feldresten.jpg\",\"datePublished\":\"2019-02-09T10:35:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/biog-biogas.com\\\/it\\\/dt_testimonials\\\/josef-hoeckner\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/biog-biogas.com\\\/it\\\/dt_testimonials\\\/josef-hoeckner\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/biog-biogas.com\\\/it\\\/dt_testimonials\\\/josef-hoeckner\\\/#primaryimage\",\"url\":\"https:\\\/\\\/biog-biogas.com\\\/wp-content\\\/uploads\\\/josef-hoeckner-mit-feldresten.jpg\",\"contentUrl\":\"https:\\\/\\\/biog-biogas.com\\\/wp-content\\\/uploads\\\/josef-hoeckner-mit-feldresten.jpg\",\"width\":1618,\"height\":1080,\"caption\":\"Josef H\u00f6ckner, Responsabile di BioG GmbH, con paglia di granturco fra le mani\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/biog-biogas.com\\\/it\\\/dt_testimonials\\\/josef-hoeckner\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/biog-biogas.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Testimonianze\",\"item\":\"https:\\\/\\\/biog-biogas.com\\\/it\\\/dt_testimonials\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Josef H\u00f6ckner\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/biog-biogas.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/biog-biogas.com\\\/it\\\/\",\"name\":\"BIOG\",\"description\":\"Solutions for green energy\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/biog-biogas.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Josef H\u00f6ckner - BIOG","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/biog-biogas.com\/it\/dt_testimonials\/josef-hoeckner\/","og_locale":"it_IT","og_type":"article","og_title":"Josef H\u00f6ckner - BIOG","og_description":"Siamo diventati specialisti nell\u2019utilizzo di residui in diverse forme e strutture. Grazie al nostro know-how aiutiamo a realizzare in modo semplice ed economico la catena di valore dal raccolto fino all\u2019impiego nel processo di fermentazione.","og_url":"https:\/\/biog-biogas.com\/it\/dt_testimonials\/josef-hoeckner\/","og_site_name":"BIOG","og_image":[{"width":1618,"height":1080,"url":"https:\/\/biog-biogas.com\/wp-content\/uploads\/josef-hoeckner-mit-feldresten.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/biog-biogas.com\/it\/dt_testimonials\/josef-hoeckner\/","url":"https:\/\/biog-biogas.com\/it\/dt_testimonials\/josef-hoeckner\/","name":"Josef H\u00f6ckner - BIOG","isPartOf":{"@id":"https:\/\/biog-biogas.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/biog-biogas.com\/it\/dt_testimonials\/josef-hoeckner\/#primaryimage"},"image":{"@id":"https:\/\/biog-biogas.com\/it\/dt_testimonials\/josef-hoeckner\/#primaryimage"},"thumbnailUrl":"https:\/\/biog-biogas.com\/wp-content\/uploads\/josef-hoeckner-mit-feldresten.jpg","datePublished":"2019-02-09T10:35:40+00:00","breadcrumb":{"@id":"https:\/\/biog-biogas.com\/it\/dt_testimonials\/josef-hoeckner\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/biog-biogas.com\/it\/dt_testimonials\/josef-hoeckner\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/biog-biogas.com\/it\/dt_testimonials\/josef-hoeckner\/#primaryimage","url":"https:\/\/biog-biogas.com\/wp-content\/uploads\/josef-hoeckner-mit-feldresten.jpg","contentUrl":"https:\/\/biog-biogas.com\/wp-content\/uploads\/josef-hoeckner-mit-feldresten.jpg","width":1618,"height":1080,"caption":"Josef H\u00f6ckner, Responsabile di BioG GmbH, con paglia di granturco fra le mani"},{"@type":"BreadcrumbList","@id":"https:\/\/biog-biogas.com\/it\/dt_testimonials\/josef-hoeckner\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/biog-biogas.com\/it\/"},{"@type":"ListItem","position":2,"name":"Testimonianze","item":"https:\/\/biog-biogas.com\/it\/dt_testimonials\/"},{"@type":"ListItem","position":3,"name":"Josef H\u00f6ckner"}]},{"@type":"WebSite","@id":"https:\/\/biog-biogas.com\/it\/#website","url":"https:\/\/biog-biogas.com\/it\/","name":"BIOG","description":"Solutions for green energy","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/biog-biogas.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/biog-biogas.com\/it\/wp-json\/wp\/v2\/dt_testimonials\/2517","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/biog-biogas.com\/it\/wp-json\/wp\/v2\/dt_testimonials"}],"about":[{"href":"https:\/\/biog-biogas.com\/it\/wp-json\/wp\/v2\/types\/dt_testimonials"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/biog-biogas.com\/it\/wp-json\/wp\/v2\/media\/535"}],"wp:attachment":[{"href":"https:\/\/biog-biogas.com\/it\/wp-json\/wp\/v2\/media?parent=2517"}],"wp:term":[{"taxonomy":"dt_testimonials_category","embeddable":true,"href":"https:\/\/biog-biogas.com\/it\/wp-json\/wp\/v2\/dt_testimonials_category?post=2517"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}